{"id":23323,"date":"2024-11-10T05:52:49","date_gmt":"2024-11-10T05:52:49","guid":{"rendered":"https:\/\/www.metlaninst.com\/?page_id=23323"},"modified":"2025-08-30T08:26:52","modified_gmt":"2025-08-30T08:26:52","slug":"debitmetres-a-effet-coriolis","status":"publish","type":"page","link":"https:\/\/metlaninst.com\/fr\/debitmetres-a-effet-coriolis\/","title":{"rendered":"D\u00e9bitm\u00e8tres \u00e0 effet Coriolis"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"23323\" class=\"elementor elementor-23323\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0a5e4b e-flex e-con-boxed e-con e-parent\" data-id=\"e0a5e4b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-230da54 e-con-full elementor-hidden-mobile catpage-left-column e-flex e-con e-child\" data-id=\"230da54\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8bb2ca9 elementor-widget elementor-widget-sidebar\" data-id=\"8bb2ca9\" data-element_type=\"widget\" data-widget_type=\"sidebar.default\">\n\t\t\t\t\t<section id=\"custom_product_categories-2\" class=\"widget-container woocommerce widget_product_categories\"><div class=\"widget-title-wrapper sidebar-industries-title\"><h3 class=\"widget-title heading-title\">Cat\u00e9gories<\/h3><\/div><ul class=\"product-categories\"><li class=\"cat-item cat-item-26324\"> <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-massiques-thermiques\/\">D\u00e9bitm\u00e8tres massiques thermiques<\/a><\/li><li class=\"cat-item cat-item-25731\"> <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-a-deplacement-positif\/\">D\u00e9bitm\u00e8tres \u00e0 d\u00e9placement positif<\/a><\/li><li class=\"cat-item cat-item-26711\"> <a href=\"https:\/\/metlaninst.com\/fr\/controleur-de-debitmetre-massique-a-faible-debit\/\">Mass Flow Meter \/ Controller<\/a><\/li><li class=\"cat-item cat-item-23323 current\"> <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-a-effet-coriolis\/\">D\u00e9bitm\u00e8tres \u00e0 effet Coriolis<\/a><\/li><li class=\"cat-item cat-item-22540\"> <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-magnetiques\/\">D\u00e9bitm\u00e8tres magn\u00e9tiques<\/a><\/li><li class=\"cat-item cat-item-22583\"> <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-a-vortex\/\">D\u00e9bitm\u00e8tres \u00e0 vortex<\/a><\/li><li class=\"cat-item cat-item-22590\"> <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-a-turbine\/\">D\u00e9bitm\u00e8tres \u00e0 turbine<\/a><\/li><li class=\"cat-item cat-item-26423\"> <a href=\"https:\/\/metlaninst.com\/fr\/debitmetre-de-gaz-a-ultrasons\/\">D\u00e9bitm\u00e8tre de gaz \u00e0 ultrasons<\/a><\/li><li class=\"cat-item cat-item-22636\"> <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-a-pression-differentielle\/\">D\u00e9bitm\u00e8tres \u00e0 pression diff\u00e9rentielle<\/a><\/li><li class=\"cat-item cat-item-25547\"> <a href=\"https:\/\/metlaninst.com\/fr\/rotametres-debitmetre\/\">Rotam\u00e8tres<\/a><\/li><\/ul><div class=\"widget-title-wrapper sidebar-industries-title\"><h3 class=\"widget-title heading-title\">Applications<\/h3><\/div><ul class=\"product-categories\"><li class=\"cat-item cat-item-23018\"> <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-dhuile\/\">D\u00e9bitm\u00e8tres d'huile<\/a><\/li><li class=\"cat-item cat-item-25691\"> <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-de-gaz\/\">D\u00e9bitm\u00e8tres de gaz<\/a><\/li><li class=\"cat-item cat-item-23875\"> <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-de-vapeur\/\">D\u00e9bitm\u00e8tres de vapeur<\/a><\/li><li class=\"cat-item cat-item-22970\"> <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-deau\/\">D\u00e9bitm\u00e8tres d'eau<\/a><\/li><\/ul><div class=\"widget-title-wrapper sidebar-industries-title\"><h3 class=\"widget-title heading-title\">Others<\/h3><\/div><ul class=\"product-categories\"><li class=\"cat-item cat-item-27506\"> <a href=\"https:\/\/metlaninst.com\/fr\/dew-point-meter\/\">Dew Point Meter<\/a><\/li><\/ul><\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ac7bda e-con-full catpage-right-column e-flex e-con e-child\" data-id=\"7ac7bda\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a474b0a elementor-widget elementor-widget-heading\" data-id=\"a474b0a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">D\u00e9bitm\u00e8tres \u00e0 effet Coriolis<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3197d7 elementor-widget elementor-widget-ts-products\" data-id=\"a3197d7\" data-element_type=\"widget\" data-widget_type=\"ts-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ts-product-wrapper ts-shortcode ts-product woocommerce columns-3 recent title-default product-default\" >\n\t\t\n\t\t\t\t\t\t\n\t\t\t<div class=\"content-wrapper\">\n\t\t\t\t<div class=\"products\"><section class=\"product type-product post-26407 status-publish first instock product_cat-coriolis-flow-meters product_cat-air-flow-meters product_cat-gas-flow-meters product_cat-liquid-flow-meters product_cat-oil-flow-meters product_cat-steam-flow-meters has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-product_id=\"26407\">\n\t<div class=\"product-wrapper\">\n\t\t\t\n\t\t<div class=\"thumbnail-wrapper\">\n\t\t\t<a href=\"https:\/\/metlaninst.com\/fr\/p\/debitmetre-massique-coriolis-w-shape-mtd-acmw\/\">\n\n\t\t\t\t<figure class=\"no-back-image\"><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/www.metlaninst.com\/wp-content\/themes\/loobek\/images\/prod_loading.gif\" data-src=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2025\/02\/Coriolis-Mass-Flow-Meter-W-Shape-MTD-ACMW-600x600.webp\" class=\"attachment-shop_catalog wp-post-image ts-lazy-load\" alt=\"D\u00e9bitm\u00e8tre massique Coriolis Forme W MTD-ACMW\" width=\"600\" height=\"600\" \/><\/figure>\n\t\t\t<\/a>\n\t\t\t\t\t<div class=\"product-label\">\n\t\t<\/div>\n\t<div class=\"product-group-button\"><div class=\"button-in quickshop\"><a class=\"quickshop\" href=\"#\" data-product_id=\"26407\"><span class=\"ts-tooltip button-tooltip\">Vue rapide<\/span><\/a><\/div><\/div>\t\t\t\n\t\t<\/div>\n\t\t<div class=\"meta-wrapper\">\n\t\t\t<div class=\"ts-product-galleries\"><div data-thumb=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2025\/02\/Coriolis-Mass-Flow-Meter-W-Shape-MTD-ACMW-600x600.webp\" class=\"active\"><img decoding=\"async\" src=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2025\/02\/Coriolis-Mass-Flow-Meter-W-Shape-MTD-ACMW-600x600.webp\" loading=\"lazy\" alt=\"\" \/><\/div><div data-thumb=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2025\/02\/Coriolis-Mass-Flowmeter-W-Shape-MTD-ACMW-600x600.webp\" class=\"\"><img decoding=\"async\" src=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2025\/02\/Coriolis-Mass-Flowmeter-W-Shape-MTD-ACMW-600x600.webp\" loading=\"lazy\" alt=\"\" \/><\/div><\/div><h3 class=\"heading-title product-name\"><a href=\"https:\/\/metlaninst.com\/fr\/p\/debitmetre-massique-coriolis-w-shape-mtd-acmw\/\">D\u00e9bitm\u00e8tre massique Coriolis forme W (MTD-ACMW)<\/a><\/h3><div class=\"product-sku\"><span>SKU<\/span>MTD-ACMW<\/div><div id=\"category-attribute-list\"><h5 class=\"attribute-loop-label\">Pr\u00e9cision<\/h5><p>\u00b10,1 % ; \u00b10,15 % ; \u00b10,2 % ; \u00b10,5 %<\/p>\n<h5 class=\"attribute-loop-label\">Plage de mesure<\/h5><p>8-1500000 kg\/h (17 - 3306930 lb\/h)<\/p>\n<h5 class=\"attribute-loop-label\">Gamme de temp\u00e9rature moyenne<\/h5><p>Type d'int\u00e9gration : (-50~+125)\u2103<br \/>\nType de fractionnement : (-200~+350)\u2103<\/p>\n<h5 class=\"attribute-loop-label\">Pression max. Pression de traitement<\/h5><p>250 bar (3626 psi)<\/p>\n<h5 class=\"attribute-loop-label\">Tube de mesure<\/h5><p>Acier inoxydable aust\u00e9nitique (316\/316L) et autres sur demande<\/p>\n<\/div><div class=\"product-group-button-meta\"><\/div>\t\t<\/div>\n\t<\/div>\n<\/section><section class=\"product type-product post-26402 status-publish instock product_cat-coriolis-flow-meters product_cat-air-flow-meters product_cat-gas-flow-meters product_cat-liquid-flow-meters product_cat-oil-flow-meters product_cat-steam-flow-meters has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-product_id=\"26402\">\n\t<div class=\"product-wrapper\">\n\t\t\t\n\t\t<div class=\"thumbnail-wrapper\">\n\t\t\t<a href=\"https:\/\/metlaninst.com\/fr\/p\/debitmetre-massique-coriolis-forme-c-mtd-acmc\/\">\n\n\t\t\t\t<figure class=\"no-back-image\"><img decoding=\"async\" src=\"http:\/\/www.metlaninst.com\/wp-content\/themes\/loobek\/images\/prod_loading.gif\" data-src=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2025\/02\/Coriolis-Mass-Flow-Meter-C-Shape-MTD-ACMC-600x600.webp\" class=\"attachment-shop_catalog wp-post-image ts-lazy-load\" alt=\"D\u00e9bitm\u00e8tre massique Coriolis Forme C MTD-ACMC\" width=\"600\" height=\"600\" \/><\/figure>\n\t\t\t<\/a>\n\t\t\t\t\t<div class=\"product-label\">\n\t\t<\/div>\n\t<div class=\"product-group-button\"><div class=\"button-in quickshop\"><a class=\"quickshop\" href=\"#\" data-product_id=\"26402\"><span class=\"ts-tooltip button-tooltip\">Vue rapide<\/span><\/a><\/div><\/div>\t\t\t\n\t\t<\/div>\n\t\t<div class=\"meta-wrapper\">\n\t\t\t<div class=\"ts-product-galleries\"><div data-thumb=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2025\/02\/Coriolis-Mass-Flow-Meter-C-Shape-MTD-ACMC-600x600.webp\" class=\"active\"><img decoding=\"async\" src=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2025\/02\/Coriolis-Mass-Flow-Meter-C-Shape-MTD-ACMC-600x600.webp\" loading=\"lazy\" alt=\"\" \/><\/div><div data-thumb=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2025\/02\/Coriolis-Mass-Flowmeter-C-Shape-MTD-ACMC-600x600.webp\" class=\"\"><img decoding=\"async\" src=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2025\/02\/Coriolis-Mass-Flowmeter-C-Shape-MTD-ACMC-600x600.webp\" loading=\"lazy\" alt=\"\" \/><\/div><\/div><h3 class=\"heading-title product-name\"><a href=\"https:\/\/metlaninst.com\/fr\/p\/debitmetre-massique-coriolis-forme-c-mtd-acmc\/\">D\u00e9bitm\u00e8tre massique Coriolis forme C (MTD-ACMC)<\/a><\/h3><div class=\"product-sku\"><span>SKU<\/span>MTD-ACMC<\/div><div id=\"category-attribute-list\"><h5 class=\"attribute-loop-label\">Pr\u00e9cision<\/h5><p>\u00b10,1 % ; \u00b10,15 % ; \u00b10,2 % ; \u00b10,5 %<\/p>\n<h5 class=\"attribute-loop-label\">Plage de mesure<\/h5><p>500-200000 kg\/h (1100-440900 lb\/h)<\/p>\n<h5 class=\"attribute-loop-label\">Gamme de temp\u00e9rature moyenne<\/h5><p>Type d'int\u00e9gration : (-50~+125)\u2103<br \/>\nType de fractionnement : (-200~+350)\u2103<\/p>\n<h5 class=\"attribute-loop-label\">Pression max. Pression de traitement<\/h5><p>250 bar (3626 psi)<\/p>\n<h5 class=\"attribute-loop-label\">Tube de mesure<\/h5><p>Acier inoxydable aust\u00e9nitique (316\/316L) et autres sur demande<\/p>\n<\/div><div class=\"product-group-button-meta\"><\/div>\t\t<\/div>\n\t<\/div>\n<\/section><section class=\"product type-product post-23332 status-publish last instock product_cat-coriolis-flow-meters product_cat-uncategorized has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-product_id=\"23332\">\n\t<div class=\"product-wrapper\">\n\t\t\t\n\t\t<div class=\"thumbnail-wrapper\">\n\t\t\t<a href=\"https:\/\/metlaninst.com\/fr\/p\/debitmetres-massiques-a-effet-coriolis-pour-les-applications-de-procedes-avances-masse-a\/\">\n\n\t\t\t\t<figure class=\"no-back-image\"><img decoding=\"async\" src=\"http:\/\/www.metlaninst.com\/wp-content\/themes\/loobek\/images\/prod_loading.gif\" data-src=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2024\/11\/MASS-A-Coriolis-Mass-Flow-Meters-for-Advanced-Process-Applications-600x600.jpg\" class=\"attachment-shop_catalog wp-post-image ts-lazy-load\" alt=\"\" width=\"600\" height=\"600\" \/><\/figure>\n\t\t\t<\/a>\n\t\t\t\t\t<div class=\"product-label\">\n\t\t<\/div>\n\t<div class=\"product-group-button\"><div class=\"button-in quickshop\"><a class=\"quickshop\" href=\"#\" data-product_id=\"23332\"><span class=\"ts-tooltip button-tooltip\">Vue rapide<\/span><\/a><\/div><\/div>\t\t\t\n\t\t<\/div>\n\t\t<div class=\"meta-wrapper\">\n\t\t\t<div class=\"ts-product-galleries\"><div data-thumb=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2024\/11\/MASS-A-Coriolis-Mass-Flow-Meters-for-Advanced-Process-Applications-600x600.jpg\" class=\"active\"><img decoding=\"async\" src=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2024\/11\/MASS-A-Coriolis-Mass-Flow-Meters-for-Advanced-Process-Applications-600x600.jpg\" loading=\"lazy\" alt=\"\" \/><\/div><\/div><h3 class=\"heading-title product-name\"><a href=\"https:\/\/metlaninst.com\/fr\/p\/debitmetres-massiques-a-effet-coriolis-pour-les-applications-de-procedes-avances-masse-a\/\">D\u00e9bitm\u00e8tres massiques \u00e0 effet Coriolis pour les applications de proc\u00e9d\u00e9s avanc\u00e9s (MASS-A)<\/a><\/h3><div class=\"product-sku\"><span>SKU<\/span>MASS-A<\/div><div id=\"category-attribute-list\"><h5 class=\"attribute-loop-label\">Pr\u00e9cision<\/h5><p>Standard : \u00b10,5 %, Option : \u00b10,2 % ; \u00b10,15 %<\/p>\n<h5 class=\"attribute-loop-label\">Plage de mesure<\/h5><p>0-30000 kg\/min (0-66138 lb\/min)<\/p>\n<h5 class=\"attribute-loop-label\">Gamme de temp\u00e9rature moyenne<\/h5><p>De -40 \u00e0 185\u00b0F (de -40 \u00e0 85\u00b0C)<\/p>\n<h5 class=\"attribute-loop-label\">Pression max. Pression de traitement<\/h5><p>100 bar (1450.38 psi)<\/p>\n<h5 class=\"attribute-loop-label\">Tube de mesure<\/h5><p>Acier inoxydable aust\u00e9nitique (316L), Hastelloy C et autres sur demande<\/p>\n<\/div><div class=\"product-group-button-meta\"><\/div>\t\t<\/div>\n\t<\/div>\n<\/section><section class=\"product type-product post-23336 status-publish first instock product_cat-coriolis-flow-meters product_cat-uncategorized has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-product_id=\"23336\">\n\t<div class=\"product-wrapper\">\n\t\t\t\n\t\t<div class=\"thumbnail-wrapper\">\n\t\t\t<a href=\"https:\/\/metlaninst.com\/fr\/p\/debitmetres-massiques-a-effet-coriolis-pour-les-applications-a-faible-debit-et-de-dosage-masse-l\/\">\n\n\t\t\t\t<figure class=\"no-back-image\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.metlaninst.com\/wp-content\/themes\/loobek\/images\/prod_loading.gif\" data-src=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2024\/11\/MASS-L-Coriolis-Mass-Flow-Meters-for-Low-Flow-and-Dosing-Applications-600x600.jpg\" class=\"attachment-shop_catalog wp-post-image ts-lazy-load\" alt=\"\" width=\"600\" height=\"600\" \/><\/figure>\n\t\t\t<\/a>\n\t\t\t\t\t<div class=\"product-label\">\n\t\t<\/div>\n\t<div class=\"product-group-button\"><div class=\"button-in quickshop\"><a class=\"quickshop\" href=\"#\" data-product_id=\"23336\"><span class=\"ts-tooltip button-tooltip\">Vue rapide<\/span><\/a><\/div><\/div>\t\t\t\n\t\t<\/div>\n\t\t<div class=\"meta-wrapper\">\n\t\t\t<div class=\"ts-product-galleries\"><div data-thumb=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2024\/11\/MASS-L-Coriolis-Mass-Flow-Meters-for-Low-Flow-and-Dosing-Applications-600x600.jpg\" class=\"active\"><img decoding=\"async\" src=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2024\/11\/MASS-L-Coriolis-Mass-Flow-Meters-for-Low-Flow-and-Dosing-Applications-600x600.jpg\" loading=\"lazy\" alt=\"\" \/><\/div><\/div><h3 class=\"heading-title product-name\"><a href=\"https:\/\/metlaninst.com\/fr\/p\/debitmetres-massiques-a-effet-coriolis-pour-les-applications-a-faible-debit-et-de-dosage-masse-l\/\">D\u00e9bitm\u00e8tres massiques Coriolis pour les applications \u00e0 faible d\u00e9bit et de dosage (MASS-L)<\/a><\/h3><div class=\"product-sku\"><span>SKU<\/span>MASS-L<\/div><div id=\"category-attribute-list\"><h5 class=\"attribute-loop-label\">Pr\u00e9cision<\/h5><p>Standard : \u00b10,5 %, Option : \u00b10,2 % ; \u00b10,15 %<\/p>\n<h5 class=\"attribute-loop-label\">Plage de mesure<\/h5><p>0-2900 kg\/min (0-6393 lb\/min)<\/p>\n<h5 class=\"attribute-loop-label\">Gamme de temp\u00e9rature moyenne<\/h5><p>De -40 \u00e0 185\u00b0F (de -40 \u00e0 85\u00b0C)<\/p>\n<h5 class=\"attribute-loop-label\">Pression max. Pression de traitement<\/h5><p>875 bar (12 689,83 psi)<\/p>\n<h5 class=\"attribute-loop-label\">Tube de mesure<\/h5><p>Acier inoxydable aust\u00e9nitique (316L), Hastelloy C et autres sur demande<\/p>\n<\/div><div class=\"product-group-button-meta\"><\/div>\t\t<\/div>\n\t<\/div>\n<\/section><section class=\"product type-product post-23340 status-publish instock product_cat-coriolis-flow-meters product_cat-uncategorized has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-product_id=\"23340\">\n\t<div class=\"product-wrapper\">\n\t\t\t\n\t\t<div class=\"thumbnail-wrapper\">\n\t\t\t<a href=\"https:\/\/metlaninst.com\/fr\/p\/debitmetres-massiques-a-effet-coriolis-pour-applications-cryogeniques-masse-c\/\">\n\n\t\t\t\t<figure class=\"no-back-image\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.metlaninst.com\/wp-content\/themes\/loobek\/images\/prod_loading.gif\" data-src=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2024\/11\/MASS-C-Coriolis-Mass-Flow-Meters-for-Cryogenic-Temperature-Media-600x600.jpg\" class=\"attachment-shop_catalog wp-post-image ts-lazy-load\" alt=\"D\u00e9bitm\u00e8tres massiques \u00e0 effet Coriolis MASS-C pour les fluides \u00e0 temp\u00e9rature cryog\u00e9nique\" width=\"600\" height=\"600\" \/><\/figure>\n\t\t\t<\/a>\n\t\t\t\t\t<div class=\"product-label\">\n\t\t<\/div>\n\t<div class=\"product-group-button\"><div class=\"button-in quickshop\"><a class=\"quickshop\" href=\"#\" data-product_id=\"23340\"><span class=\"ts-tooltip button-tooltip\">Vue rapide<\/span><\/a><\/div><\/div>\t\t\t\n\t\t<\/div>\n\t\t<div class=\"meta-wrapper\">\n\t\t\t<div class=\"ts-product-galleries\"><div data-thumb=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2024\/11\/MASS-C-Coriolis-Mass-Flow-Meters-for-Cryogenic-Temperature-Media-600x600.jpg\" class=\"active\"><img decoding=\"async\" src=\"https:\/\/metlaninst.com\/wp-content\/uploads\/2024\/11\/MASS-C-Coriolis-Mass-Flow-Meters-for-Cryogenic-Temperature-Media-600x600.jpg\" loading=\"lazy\" alt=\"\" \/><\/div><\/div><h3 class=\"heading-title product-name\"><a href=\"https:\/\/metlaninst.com\/fr\/p\/debitmetres-massiques-a-effet-coriolis-pour-applications-cryogeniques-masse-c\/\">D\u00e9bitm\u00e8tres massiques \u00e0 effet Coriolis pour applications cryog\u00e9niques (MASS-C)<\/a><\/h3><div class=\"product-sku\"><span>SKU<\/span>MASS-C<\/div><div id=\"category-attribute-list\"><h5 class=\"attribute-loop-label\">Pr\u00e9cision<\/h5><p>Standard : \u00b10,5 %, Option : \u00b10,2 % ; \u00b10,15 %<\/p>\n<h5 class=\"attribute-loop-label\">Plage de mesure<\/h5><p>0-70 kg\/min (0-154 lb\/min)<\/p>\n<h5 class=\"attribute-loop-label\">Gamme de temp\u00e9rature moyenne<\/h5><p>-328 \u00e0 185\u00b0F (-200 \u00e0 85\u00b0C)<\/p>\n<h5 class=\"attribute-loop-label\">Pression max. Pression de traitement<\/h5><p>40 bar (580.15 psi)<\/p>\n<h5 class=\"attribute-loop-label\">Tube de mesure<\/h5><p>Acier inoxydable aust\u00e9nitique (316L), Hastelloy C et autres sur demande<\/p>\n<\/div><div class=\"product-group-button-meta\"><\/div>\t\t<\/div>\n\t<\/div>\n<\/section><\/div>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c91ff9a e-con-full e-flex e-con e-child\" data-id=\"c91ff9a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27047e9 elementor-widget elementor-widget-text-editor\" data-id=\"27047e9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Qu'est-ce qu'un d\u00e9bitm\u00e8tre \u00e0 effet Coriolis ?<\/h2><div>Un d\u00e9bitm\u00e8tre \u00e0 effet Coriolis est un appareil de mesure de d\u00e9bit tr\u00e8s pr\u00e9cis qui mesure directement le d\u00e9bit massique d'un fluide, par opposition \u00e0 la mesure de son d\u00e9bit volum\u00e9trique. Contrairement aux d\u00e9bitm\u00e8tres traditionnels, les d\u00e9bitm\u00e8tres Coriolis ne se basent pas sur la vitesse ou la mesure volum\u00e9trique du fluide, mais sur les principes de l'effet Coriolis. Cet effet permet au compteur de Coriolis de mesurer directement le d\u00e9bit massique, ce qui le rend particuli\u00e8rement utile dans les applications o\u00f9 les variations de densit\u00e9, de viscosit\u00e9 et de temp\u00e9rature peuvent avoir un impact sur la pr\u00e9cision de la mesure.<\/div><h3>Comprendre l'effet de Coriolis<\/h3><div>L'effet de Coriolis est une d\u00e9viation des objets en mouvement lorsqu'ils sont vus dans un cadre de r\u00e9f\u00e9rence en rotation. Dans le contexte de la mesure du d\u00e9bit, cet effet est exploit\u00e9 en faisant vibrer un tube d'\u00e9coulement dans lequel passe le fluide. Lorsque le fluide se d\u00e9place dans le tube vibrant, il provoque un changement dans le mod\u00e8le de vibration en raison des forces d'inertie agissant sur le fluide : c'est l'effet de Coriolis en action.<\/div><h3>M\u00e9canisme de fonctionnement<\/h3><ol class=\"cat-page\"><li><h5>Vibration du tube :<\/h5><div>Une unit\u00e9 d'entra\u00eenement \u00e9lectromagn\u00e9tique fait vibrer le tube d'\u00e9coulement \u00e0 sa fr\u00e9quence naturelle. Cette vibration se produit perpendiculairement \u00e0 la direction de l'\u00e9coulement du fluide.<\/div><\/li><li><h5>\u00c9coulement du fluide dans le tube vibrant :<\/h5><div>Lorsque le fluide p\u00e9n\u00e8tre dans le tube vibrant, il commence \u00e0 interagir avec les vibrations du tube.<\/div><\/li><li><h5>D\u00e9tection de d\u00e9phasage :<\/h5><div>Des capteurs situ\u00e9s \u00e0 l'entr\u00e9e et \u00e0 la sortie du tube d\u00e9tectent la diff\u00e9rence de temps (d\u00e9phasage) entre les vibrations \u00e0 ces deux points.<\/div><\/li><li><h5>Calcul du d\u00e9bit massique :<\/h5><div>Le d\u00e9phasage est directement proportionnel au d\u00e9bit massique du fluide. Plus le d\u00e9bit massique est \u00e9lev\u00e9, plus le d\u00e9phasage est important. L'\u00e9lectronique du d\u00e9bitm\u00e8tre calcule le d\u00e9bit massique sur la base de ce d\u00e9phasage.<\/div><\/li><li><h5>Mesure de la densit\u00e9 et de la temp\u00e9rature :<\/h5><div>De nombreux d\u00e9bitm\u00e8tres \u00e0 effet Coriolis mesurent \u00e9galement la densit\u00e9 du fluide en analysant les variations de la fr\u00e9quence de vibration, ainsi que la temp\u00e9rature \u00e0 l'aide de capteurs de temp\u00e9rature int\u00e9gr\u00e9s. Cela permet d'effectuer des calculs suppl\u00e9mentaires, tels que le d\u00e9bit volum\u00e9trique et l'analyse de la composition du fluide.<\/div><\/li><\/ol><h2>Conception des tubes des d\u00e9bitm\u00e8tres \u00e0 effet Coriolis<\/h2><div>Les d\u00e9bitm\u00e8tres \u00e0 effet Coriolis se pr\u00e9sentent sous diff\u00e9rentes formes de tubes, chacune \u00e9tant adapt\u00e9e \u00e0 des applications sp\u00e9cifiques :<\/div><ol class=\"cat-page\"><li><h5>Tubes en forme de U<\/h5><ul><li><b>Description :<\/b>Comprend un ou plusieurs tubes en forme de U.<\/li><li><b>Avantages :<\/b><ul><li>Sensibilit\u00e9 \u00e9lev\u00e9e gr\u00e2ce au d\u00e9placement plus important caus\u00e9 par la forme en U.<\/li><li>Efficace pour mesurer de faibles d\u00e9bits.<\/li><\/ul><\/li><li><b>Limites :<\/b><ul><li>Conception plus volumineuse.<\/li><li>Perte de charge plus importante que pour les tubes droits.<\/li><\/ul><\/li><\/ul><\/li><li><h5>Tubes en forme de S (om\u00e9ga)<\/h5><ul><li><b>Description :<\/b> Ressemble \u00e0 la lettre grecque Omega (\u03a9) ou \u00e0 une forme de S.<\/li><li><b>Avantages :<\/b><ul><li>Conception compacte par rapport aux tubes en U.<\/li><li>La structure \u00e9quilibr\u00e9e r\u00e9duit les contraintes et prolonge la dur\u00e9e de vie du compteur.<\/li><\/ul><\/li><li><b>Limites :<\/b> L\u00e9g\u00e8rement moins sensibles que les tubes en U.<\/li><\/ul><\/li><li><h5>Tubes droits<\/h5><ul><li><b>Description :<\/b> Constitu\u00e9 d'un ou deux tubes droits.<\/li><li><b>Avantages :<\/b><ul><li>Perte de charge minimale.<\/li><li>Plus facile \u00e0 nettoyer, id\u00e9al pour les applications sanitaires.<\/li><li>Risque r\u00e9duit de colmatage avec des fluides visqueux ou charg\u00e9s de particules.<\/li><\/ul><\/li><li><b>Limites :<\/b><ul><li>Moins sensible aux faibles d\u00e9bits.<\/li><li>Peut n\u00e9cessiter un support plus robuste pour \u00e9viter les vibrations externes.<\/li><\/ul><\/li><\/ul><\/li><li><h5>Tubes courbes doubles<\/h5><ul><li><b>Description :<\/b> Incorporer deux tubes courbes parall\u00e8les.<\/li><li><b>Avantages :<\/b><ul><li>Am\u00e9lioration de la sensibilit\u00e9 et de la pr\u00e9cision.<\/li><li>R\u00e9duction des effets des vibrations externes.<\/li><\/ul><\/li><li><b>Limites :<\/b>Une conception plus complexe peut augmenter les co\u00fbts.<\/li><\/ul><\/li><\/ol><h2>Pr\u00e9cision du d\u00e9bitm\u00e8tre \u00e0 effet Coriolis<\/h2><div>Les d\u00e9bitm\u00e8tres \u00e0 effet Coriolis sont r\u00e9put\u00e9s pour leur grande pr\u00e9cision dans la mesure des d\u00e9bits massiques. Les plages de pr\u00e9cision typiques sont les suivantes<\/div><ul class=\"cat-page\"><li><b>Liquides :<\/b> \u00b10,1% \u00e0 \u00b10,2% de la lecture.<\/li><li><b>Gaz :<\/b> \u00b10,5% \u00e0 \u00b11,0% de la lecture.<\/li><\/ul><h3>Facteurs influen\u00e7ant la pr\u00e9cision<\/h3><ol class=\"cat-page\"><li><h5>Propri\u00e9t\u00e9s des fluides :<\/h5><div>La viscosit\u00e9, la densit\u00e9 et la temp\u00e9rature peuvent affecter les mesures, mais les compteurs \u00e0 effet Coriolis compensent efficacement ces variations.<\/div><\/li><li><h5>Conditions d'\u00e9coulement :<\/h5><div>Les flux tourbillonnants ou les profils de vitesse asym\u00e9triques peuvent introduire des erreurs. Une installation correcte permet d'att\u00e9nuer ces probl\u00e8mes.<\/div><\/li><li><h5>Vibrations externes :<\/h5><div>Les vibrations provenant d'\u00e9quipements situ\u00e9s \u00e0 proximit\u00e9 peuvent perturber le fonctionnement du compteur. Des mesures d'isolation ou d'amortissement peuvent \u00eatre n\u00e9cessaires.<\/div><\/li><li><h5>Flux \u00e0 deux phases :<\/h5><div>La pr\u00e9sence de bulles de gaz dans les liquides ou de gouttelettes de liquide dans les gaz peut affecter la pr\u00e9cision.<\/div><\/li><\/ol><h3>Am\u00e9liorer la pr\u00e9cision<\/h3><ul class=\"cat-page\"><li><b>\u00c9talonnage :<\/b> Un \u00e9talonnage r\u00e9gulier permet au compteur de conserver sa pr\u00e9cision au fil du temps.<\/li><li><b>Installation :<\/b> Le respect des directives du fabricant pour l'installation permet de minimiser les erreurs potentielles.<\/li><li><b>Entretien :<\/b> Les inspections et l'entretien de routine permettent d'\u00e9viter la d\u00e9gradation des performances.<\/li><\/ul><h2>Gamme de d\u00e9bitm\u00e8tres \u00e0 effet Coriolis<\/h2><div><b>L'autonomie<\/b>La plage de mesure, \u00e9galement connue sous le nom de rapport de r\u00e9duction, correspond \u00e0 la plage sur laquelle le d\u00e9bitm\u00e8tre peut mesurer avec pr\u00e9cision les d\u00e9bits. Les d\u00e9bitm\u00e8tres \u00e0 effet Coriolis offrent une excellente plage de mesure, typiquement :<\/div><ul class=\"cat-page\"><li><b>Ratios de rotation :<\/b> Jusqu'\u00e0 100:1 pour les liquides, ce qui signifie que le d\u00e9bit maximal est 100 fois sup\u00e9rieur au d\u00e9bit minimal que le compteur peut mesurer avec pr\u00e9cision.<\/li><\/ul><h3>Avantages d'une grande souplesse d'utilisation<\/h3><ul class=\"cat-page\"><li><b>Polyvalence :<\/b> Un seul compteur peut couvrir une large gamme de d\u00e9bits, ce qui r\u00e9duit la n\u00e9cessit\u00e9 de disposer de plusieurs compteurs.<\/li><li><b>Rentable :<\/b> R\u00e9duction des co\u00fbts d'installation et de maintenance gr\u00e2ce \u00e0 la diminution du nombre de compteurs n\u00e9cessaires.<\/li><li><b>Flexibilit\u00e9 du processus :<\/b> Id\u00e9al pour les proc\u00e9d\u00e9s \u00e0 d\u00e9bit variable.<\/li><\/ul><h2>Dimensionnement et perte de charge d'un d\u00e9bitm\u00e8tre \u00e0 effet Coriolis<\/h2><h3>Consid\u00e9rations sur la taille<\/h3><div>Le dimensionnement correct d'un d\u00e9bitm\u00e8tre \u00e0 effet Coriolis est essentiel pour obtenir des performances optimales :<\/div><ol class=\"cat-page\"><li><b>D\u00e9bit :<\/b> Le compteur doit \u00eatre dimensionn\u00e9 pour traiter le d\u00e9bit maximal attendu sans d\u00e9passer sa capacit\u00e9.<\/li><li><b>Caract\u00e9ristiques du fluide :<\/b> La viscosit\u00e9 et la densit\u00e9 affectent le fonctionnement du compteur et doivent \u00eatre prises en compte lors du dimensionnement.<\/li><li><b>Conditions du processus :<\/b> Les conditions de temp\u00e9rature et de pression peuvent influencer le choix des mat\u00e9riaux et la conception des compteurs.<\/li><\/ol><h3>Chute de pression<\/h3><ul class=\"cat-page\"><li><b>D\u00e9finition :<\/b> La r\u00e9duction de la pression lorsque le fluide passe \u00e0 travers le d\u00e9bitm\u00e8tre.<\/li><li><b>Facteurs influen\u00e7ant la perte de charge :<\/b><ul><li><b>Conception du tube :<\/b> Les tubes courbes entra\u00eenent g\u00e9n\u00e9ralement des pertes de charge plus importantes que les tubes droits.<\/li><li><b>D\u00e9bit :<\/b> Des d\u00e9bits plus \u00e9lev\u00e9s augmentent la perte de charge.<\/li><li><b>Viscosit\u00e9 du produit :<\/b> Les fluides plus visqueux entra\u00eenent des pertes de charge plus importantes.<\/li><\/ul><\/li><li><b>Att\u00e9nuation :<\/b><ul><li><b>Taille appropri\u00e9e :<\/b> Un surdimensionnement du compteur peut r\u00e9duire la perte de charge mais peut affecter la pr\u00e9cision \u00e0 faible d\u00e9bit.<\/li><li><b>S\u00e9lection de tubes :<\/b> Le choix d'un tube droit permet de minimiser la perte de charge.<\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bdd7a38 e-con-full e-flex e-con e-child\" data-id=\"bdd7a38\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f07c1f elementor-widget elementor-widget-text-editor\" data-id=\"9f07c1f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Avantages et limites du d\u00e9bitm\u00e8tre \u00e0 effet Coriolis<\/h2><table id=\"page-cat-table\"><tbody><tr><th>Avantages<\/th><th>Limites<\/th><\/tr><tr><td><ul><li><b>Mesure directe du d\u00e9bit massique :<\/b><br \/>Aucune compensation suppl\u00e9mentaire de temp\u00e9rature ou de pression n'est n\u00e9cessaire.<\/li><li><b>Haute pr\u00e9cision :<\/b><br \/>Excellent pour le transfert de garde et les applications critiques.<\/li><li><b>Mesure multi-variable :<\/b><br \/>Peut mesurer simultan\u00e9ment le d\u00e9bit massique, la densit\u00e9 et la temp\u00e9rature.<\/li><li><b>Pas de pi\u00e8ces mobiles :<\/b><br \/>Peu d'entretien et longue dur\u00e9e de vie.<\/li><li><b>Ind\u00e9pendance des fluides :<\/b><br \/>Convient pour les liquides, les gaz et les boues.<\/li><\/ul><\/td><td><ul><li><b>Co\u00fbt initial \u00e9lev\u00e9 :<\/b><br \/>Plus cher que les autres types de d\u00e9bitm\u00e8tres.<\/li><li><b>Sensible aux vibrations externes :<\/b><br \/>Peut n\u00e9cessiter des consid\u00e9rations d'installation.<\/li><li><b>Chute de pression :<\/b><br \/>Elle peut \u00eatre importante, en particulier pour les compteurs de petite taille dont les tubes sont courb\u00e9s.<\/li><li><b>Limites de taille :<\/b><br \/>Moins pratique pour les tuyaux de tr\u00e8s grand diam\u00e8tre.<\/li><li><b>Exigences d'installation :<\/b><br \/>N\u00e9cessite des conduites droites et un support pour minimiser les vibrations.<\/li><\/ul><\/td><\/tr><\/tbody><\/table><h2>Applications du d\u00e9bitm\u00e8tre \u00e0 effet Coriolis<\/h2><div>Les d\u00e9bitm\u00e8tres \u00e0 effet Coriolis sont des instruments polyvalents utilis\u00e9s dans un grand nombre d'industries :<\/div><ol class=\"cat-page\"><li><h5>P\u00e9trole et gaz<\/h5><ul><li><b>Transfert de garde<\/b>: Leur grande pr\u00e9cision les rend id\u00e9ales pour le transfert de propri\u00e9t\u00e9 des fluides.<\/li><li><b>Op\u00e9rations de m\u00e9lange<\/b>: Des mesures pr\u00e9cises garantissent des rapports de m\u00e9lange corrects.<\/li><li><b>Mesures en t\u00eate de puits<\/b>: Convient aux \u00e9coulements multiphasiques avec des configurations appropri\u00e9es.<\/li><\/ul><\/li><li><h5>Chimie et p\u00e9trochimie<\/h5><ul><li><b>Suivi des r\u00e9actions<\/b>: La mesure pr\u00e9cise du d\u00e9bit massique est essentielle pour la st\u0153chiom\u00e9trie des r\u00e9actions.<\/li><li><b>Traitement par lots<\/b>: Garantit une qualit\u00e9 de produit constante gr\u00e2ce \u00e0 un dosage pr\u00e9cis des ingr\u00e9dients.<\/li><li><b>Fluides corrosifs<\/b>: Les mat\u00e9riaux compatibles peuvent supporter des produits chimiques agressifs.<\/li><\/ul><\/li><li><h5>Alimentation et boissons<\/h5><ul><li><b>Proc\u00e9d\u00e9s hygi\u00e9niques<\/b>: Les tubes droits facilitent le nettoyage et la st\u00e9rilisation.<\/li><li><b>Mesure des ingr\u00e9dients<\/b>: Dosage pr\u00e9cis des ar\u00f4mes, des colorants et des additifs.<\/li><li><b>Production de boissons<\/b>: Contr\u00f4le des sirops et des concentr\u00e9s.<\/li><\/ul><\/li><li><h5>Produits pharmaceutiques<\/h5><ul><li><b>Dosage de pr\u00e9cision<\/b>: Essentiel pour les ingr\u00e9dients pharmaceutiques actifs (API).<\/li><li><b>Applications st\u00e9riles<\/b>: Des conceptions qui r\u00e9pondent aux normes sanitaires.<\/li><li><b>Recherche et d\u00e9veloppement<\/b>: La haute pr\u00e9cision facilite la mise \u00e0 l'\u00e9chelle du processus.<\/li><\/ul><\/li><li><h5>Eau et eaux us\u00e9es<\/h5><ul><li><b>Dosage chimique<\/b>: Mesure pr\u00e9cise des produits chimiques de traitement.<\/li><li><b>Traitement des boues<\/b>: Convient \u00e0 la mesure de boues de diff\u00e9rentes densit\u00e9s.<\/li><li><b>Surveillance des effluents<\/b>: Respect des r\u00e9glementations environnementales.<\/li><\/ul><\/li><li><h5>P\u00e2tes et papiers<\/h5><ul><li><b>Agents de blanchiment<\/b>: Mesure pr\u00e9cise de produits chimiques tels que le chlore et le peroxyde.<\/li><li><b>Rev\u00eatements et additifs<\/b>: Assurer une qualit\u00e9 constante des produits.<\/li><li><b>Traitement de la liqueur noire<\/b>: Traite efficacement les fluides \u00e0 haute viscosit\u00e9.<\/li><\/ul><\/li><\/ol><p><a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-de-gaz\/\">D\u00e9bitm\u00e8tres de gaz<\/a> | <a href=\"http:\/\/metlaninst.com\/fr\/debitmetres-dhuile\/\">D\u00e9bitm\u00e8tres d'huile<\/a> | <a href=\"https:\/\/metlaninst.com\/fr\/p\/debitmetre-de-gaz-a-tube-de-pitot-mtkb-201x\/\">Pitot Tube Flow Meters<\/a> | <a href=\"https:\/\/metlaninst.com\/fr\/controleur-de-debitmetre-massique-a-faible-debit\/\">Flow Meter Controllers<\/a> | <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-massiques-thermiques\/\">D\u00e9bitm\u00e8tres massiques thermiques<\/a> | <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-a-vortex\/\">D\u00e9bitm\u00e8tres \u00e0 vortex<\/a> | <a href=\"https:\/\/metlaninst.com\/fr\/debitmetre-de-gaz-a-ultrasons\/\">D\u00e9bitm\u00e8tres de gaz \u00e0 ultrasons<\/a> | <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-magnetiques\/\">D\u00e9bitm\u00e8tres magn\u00e9tiques<\/a> | <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-a-turbine\/\">D\u00e9bitm\u00e8tres \u00e0 turbine<\/a> | <a href=\"https:\/\/metlaninst.com\/fr\/debitmetres-a-pression-differentielle\/\">D\u00e9bitm\u00e8tres \u00e0 pression diff\u00e9rentielle<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Coriolis Flow Meters Quick view Coriolis Mass Flow Meter W Shape (MTD-ACMW) SKUMTD-ACMW Accuracy \u00b10.1 %; \u00b10.15 %; \u00b10.2 %; \u00b10.5 % Measuring Range 8-1500000 kg\/h (17 &#8211; 3306930 lb\/h) Medium Temperature Range Integrate Type: (-50~+125)\u2103 Split Type: (-200~+350)\u2103 Max. Process Pressure 250 bar (3626 psi) Measuring tube Austenitic stainless steel (316\/316L), and others on [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-23323","page","type-page","status-publish","hentry"],"rankMath":{"parentDomain":"metlaninst.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"L\u2019image en vedette devrait \u00eatre au moins 200 par 200 pixels pour \u00eatre utilis\u00e9 par Facebook et d\u2019autres sites de m\u00e9dias sociaux.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"coriolis-mass-flow-meters-for-cryogenic-applications-mass-c","permalinkFormat":"https:\/\/metlaninst.com\/fr\/p\/%25product%25\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/metlaninst.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":{"title":"Cat\u00e9gorie","name":"product_cat","singularLabel":"Cat\u00e9gorie","restBase":"product_cat"},"serpData":{"title":"","description":"MASS-C is the standard high performance Coriolis mass flow meter for the process industry, which is the optimum device for cryogenic media.","focusKeywords":"coriolis mass flow meter","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"identifiant","primaryTerm":171,"authorName":"Suki","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":true},"powerWords":["absolument","amazement","astonishing","authentique","beau","bien-\u00eatre","brillant","captivant","charismatique","choc","clair","compl\u00e8tement","confidentiel","confiance","cons\u00e9quent","cr\u00e9atif","d\u00e9finitivement","d\u00e9licieux","d\u00e9montrer","d\u00e9p\u00eachez-vous","d\u00e9termin\u00e9","digne","dynamique","\u00e9blouissant","\u00e9clatant","\u00e9conomique","\u00e9fficace","\u00e9l\u00e9gant","\u00e9motionnel","\u00e9nergique","\u00e9norme","\u00e9poustouflant","essentiel","\u00e9tonnant","exclusif","exp\u00e9rience","fabuleux","fantastique","formidable","fort","garanti","g\u00e9ant","g\u00e9n\u00e9reux","grandiose","gratuit","habile","harmonieux","historique","hors pair","important","incroyable","indispensable","inoubliable","inspirant","innovant","intense","invention","irr\u00e9sistible","l\u00e9gendaire","lumineux","luxe","magique","magnifique","majestueux","marquant","merveilleux","miraculeux","motivant","n\u00e9cessaire","nouvelle","officiel","parfait","passionn\u00e9","persuasif","ph\u00e9nom\u00e9nal","plaisir","populaire","pouvoir","prestigieux","prodigieux","profond","prosp\u00e8re","puissant","qualit\u00e9","radieux","rapide","r\u00e9ussi","r\u00e9volutionnaire","satisfait","s\u00e9curit\u00e9","sensationnel","serein","somptueux","splendide","sublime","surprenant","talentueux","terrifiant","unique","valeur","vibrant","victorieux","vif","vraiment","z\u00e9l\u00e9"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":false,"hasBreadcrumb":false},"homeUrl":"https:\/\/metlaninst.com\/fr","objectID":23340,"objectType":"post","locale":"fr","localeFull":"fr_FR","overlayImages":{"play":{"name":"Ic\u00f4ne de lecture","url":"https:\/\/metlaninst.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/www\/wwwroot\/www.metlaninst.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Ic\u00f4ne GIF","url":"https:\/\/metlaninst.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/www\/wwwroot\/www.metlaninst.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/metlaninst.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fmetlaninst.com%2Ffr&r=https%3A%2F%2Fmetlaninst.com%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fpages%2F23323%3Fnonce%3D52c3a01a0f","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/metlaninst.com\/wp-content\/uploads\/2024\/09\/cropped-Metlan-Instrument-Icon-32x32.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Mettre \u00e0 niveau","trendsPreviewImage":"https:\/\/metlaninst.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["absolument","amazement","astonishing","authentique","beau","bien-\u00eatre","brillant","captivant","charismatique","choc","clair","compl\u00e8tement","confidentiel","confiance","cons\u00e9quent","cr\u00e9atif","d\u00e9finitivement","d\u00e9licieux","d\u00e9montrer","d\u00e9p\u00eachez-vous","d\u00e9termin\u00e9","digne","dynamique","\u00e9blouissant","\u00e9clatant","\u00e9conomique","\u00e9fficace","\u00e9l\u00e9gant","\u00e9motionnel","\u00e9nergique","\u00e9norme","\u00e9poustouflant","essentiel","\u00e9tonnant","exclusif","exp\u00e9rience","fabuleux","fantastique","formidable","fort","garanti","g\u00e9ant","g\u00e9n\u00e9reux","grandiose","gratuit","habile","harmonieux","historique","hors pair","important","incroyable","indispensable","inoubliable","inspirant","innovant","intense","invention","irr\u00e9sistible","l\u00e9gendaire","lumineux","luxe","magique","magnifique","majestueux","marquant","merveilleux","miraculeux","motivant","n\u00e9cessaire","nouvelle","officiel","parfait","passionn\u00e9","persuasif","ph\u00e9nom\u00e9nal","plaisir","populaire","pouvoir","prestigieux","prodigieux","profond","prosp\u00e8re","puissant","qualit\u00e9","radieux","rapide","r\u00e9ussi","r\u00e9volutionnaire","satisfait","s\u00e9curit\u00e9","sensationnel","serein","somptueux","splendide","sublime","surprenant","talentueux","terrifiant","unique","valeur","vibrant","victorieux","vif","vraiment","z\u00e9l\u00e9"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/metlaninst.com\/fr\/wp-json\/wp\/v2\/pages\/23323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metlaninst.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/metlaninst.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/metlaninst.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/metlaninst.com\/fr\/wp-json\/wp\/v2\/comments?post=23323"}],"version-history":[{"count":41,"href":"https:\/\/metlaninst.com\/fr\/wp-json\/wp\/v2\/pages\/23323\/revisions"}],"predecessor-version":[{"id":27441,"href":"https:\/\/metlaninst.com\/fr\/wp-json\/wp\/v2\/pages\/23323\/revisions\/27441"}],"wp:attachment":[{"href":"https:\/\/metlaninst.com\/fr\/wp-json\/wp\/v2\/media?parent=23323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}